{"id":3,"date":"2024-08-12T11:02:10","date_gmt":"2024-08-12T09:02:10","guid":{"rendered":"https:\/\/hcrigi.ch\/?page_id=3"},"modified":"2026-04-17T10:56:02","modified_gmt":"2026-04-17T08:56:02","slug":"datenschutzerklaerung","status":"publish","type":"page","link":"https:\/\/hcrigi.ch\/index.php\/datenschutzerklaerung\/","title":{"rendered":"Datenschutzerkl\u00e4rung"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8220;1&#8243; _builder_version=&#8220;4.21.0&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_row _builder_version=&#8220;4.21.0&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;4.21.0&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_text _builder_version=&#8220;4.27.5&#8243; _module_preset=&#8220;default&#8220; text_text_color=&#8220;#2C3E50&#8243; hover_enabled=&#8220;0&#8243; global_colors_info=&#8220;{}&#8220; sticky_enabled=&#8220;0&#8243;]<\/p>\n<h3><strong>Datenschutzerkl\u00e4rung<\/strong><\/h3>\n<p>Verantwortliche Stelle im Sinne der Datenschutzgesetze, insbesondere der EU-Datenschutzgrundverordnung (DSGVO), ist:<\/p>\n<p>HC Rigi<br \/>Strasse, Nr,<br \/>PLZ Ort<\/p>\n<p>E-Mail: <a href=\"mailto:i&#110;&#102;&#111;&#64;hc&#114;igi.c&#104;\">i&#110;&#102;o&#64;&#104;cr&#105;&#103;&#105;.ch<\/a><br \/>WebSite: <a href=\"https:\/\/hcrigi.ch\">https:\/\/www.hcrigi.ch<\/a><\/p>\n<p><strong>Allgemeiner Hinweis<br \/><\/strong>Gest\u00fctzt auf Artikel 13 der schweizerischen Bundesverfassung und den datenschutzrechtlichen Bestimmungen des Bundes (Datenschutzgesetz, DSG) hat jede Person Anspruch auf Schutz ihrer Privatsph\u00e4re sowie auf Schutz vor Missbrauch ihrer pers\u00f6nlichen Daten. Die Betreiber dieser Seiten nehmen den Schutz Ihrer pers\u00f6nlichen Daten sehr ernst. Wir behandeln Ihre personenbezogenen Daten vertraulich und entsprechend der gesetzlichen Datenschutzvorschriften sowie dieser Datenschutzerkl\u00e4rung.<\/p>\n<p>In Zusammenarbeit mit unseren Hosting-Providern bem\u00fchen wir uns, die Datenbanken so gut wie m\u00f6glich vor fremden Zugriffen, Verlusten, Missbrauch oder vor F\u00e4lschung zu sch\u00fctzen.<\/p>\n<p>Wir weisen darauf hin, dass die Daten\u00fcbertragung im Internet (z.B. bei der Kommunikation per E-Mail) Sicherheitsl\u00fccken aufweisen kann. Ein l\u00fcckenloser Schutz der Daten vor dem Zugriff durch Dritte ist nicht m\u00f6glich.<\/p>\n<p>Durch die Nutzung dieser Website erkl\u00e4ren Sie sich mit der Erhebung, Verarbeitung und Nutzung von Daten gem\u00e4ss der nachfolgenden Beschreibung einverstanden. Diese Website kann grunds\u00e4tzlich ohne Registrierung besucht werden. Dabei werden Daten wie beispielsweise aufgerufene Seiten bzw. Namen der abgerufenen Datei, Datum und Uhrzeit zu statistischen Zwecken auf dem Server gespeichert, ohne dass diese Daten unmittelbar auf Ihre Person bezogen werden. Personenbezogene Daten, insbesondere Name, Adresse oder E-Mail-Adresse werden soweit m\u00f6glich auf freiwilliger Basis erhoben. Ohne Ihre Einwilligung erfolgt keine Weitergabe der Daten an Dritte.<\/p>\n<p><strong>Bearbeitung von Personendaten<br \/><\/strong>Personendaten sind alle Angaben, die sich auf eine bestimmte oder bestimmbare Person beziehen. Eine betroffene Person ist eine Person, \u00fcber die Personendaten bearbeitet werden. Bearbeiten umfasst jeden Umgang mit Personendaten, unabh\u00e4ngig von den angewandten Mitteln und Verfahren, insbesondere das Aufbewahren, Bekanntgeben, Beschaffen, L\u00f6schen, Speichern, Ver\u00e4ndern, Vernichten und Verwenden von Personendaten.<\/p>\n<p>Wir bearbeiten Personendaten im Einklang mit dem schweizerischen Datenschutzrecht. Im \u00dcbrigen bearbeiten wir \u2013 soweit und sofern die EU-DSGVO anwendbar ist \u2013 Personendaten gem\u00e4ss folgenden Rechtsgrundlagen im Zusammenhang mit Art. 6 Abs. 1 DSGVO:<\/p>\n<ul>\n<li>lit. a) Bearbeitung von Personendaten mit Einwilligung der betroffenen Person.<\/li>\n<li>lit. b) Bearbeitung von Personendaten zur Erf\u00fcllung eines Vertrages mit der betroffenen Person sowie zur Durchf\u00fchrung entsprechender vorvertraglicher Massnahmen.<\/li>\n<li>lit. c) Bearbeitung von Personendaten zur Erf\u00fcllung einer rechtlichen Verpflichtung, der wir gem\u00e4ss allenfalls anwendbarem Recht der EU oder gem\u00e4ss allenfalls anwendbarem Recht eines Landes, in dem die DSGVO\u00a0ganz oder teilweise anwendbar ist, unterliegen.<\/li>\n<li>lit. d) Bearbeitung von Personendaten um lebenswichtige Interessen der betroffenen Person oder einer anderen nat\u00fcrlichen Person zu sch\u00fctzen.<\/li>\n<li>lit. f) Bearbeitung von Personendaten um die berechtigten Interessen von uns oder von Dritten zu wahren, sofern nicht die Grundfreiheiten und Grundrechte sowie Interessen der betroffenen Person \u00fcberwiegen. Berechtigte Interessen sind insbesondere unser betriebswirtschaftliches Interesse, unsere Website bereitstellen zu k\u00f6nnen, die Informationssicherheit, die Durchsetzung von eigenen rechtlichen Anspr\u00fcchen und die Einhaltung von schweizerischem Recht.<\/li>\n<\/ul>\n<p>Wir bearbeiten Personendaten f\u00fcr jene Dauer, die f\u00fcr den jeweiligen Zweck oder die jeweiligen Zwecke erforderlich ist. Bei l\u00e4nger dauernden Aufbewahrungspflichten aufgrund von gesetzlichen und sonstigen Pflichten, denen wir unterliegen, schr\u00e4nken wir die Bearbeitung entsprechend ein.<\/p>\n<p><strong>Datenschutzerkl\u00e4rung f\u00fcr Cookies<br \/><\/strong>Diese Website verwendet Cookies. Das sind kleine Textdateien, die es m\u00f6glich machen, auf dem Endger\u00e4t des Nutzers spezifische, auf den Nutzer bezogene Informationen zu speichern, w\u00e4hrend er die Website nutzt. Cookies erm\u00f6glichen es, insbesondere Nutzungsh\u00e4ufigkeit und Nutzeranzahl der Seiten zu ermitteln, Verhaltensweisen der Seitennutzung zu analysieren, aber auch unser Angebot kundenfreundlicher zu gestalten.\u00a0Cookies bleiben \u00fcber das Ende einer Browser-Sitzung gespeichert und k\u00f6nnen bei einem erneuten Seitenbesuch wieder aufgerufen werden. Wenn Sie das nicht w\u00fcnschen, sollten Sie Ihren Internetbrowser so einstellen, dass er die Annahme von Cookies verweigert.<\/p>\n<p>Ein genereller Widerspruch gegen den Einsatz der zu Zwecken des Onlinemarketing eingesetzten Cookies kann bei einer Vielzahl der Dienste, vor allem im Fall des Trackings, \u00fcber die US-amerikanische Seite\u00a0<a href=\"http:\/\/www.aboutads.info\/choices\/\" target=\"_blank\" rel=\"noreferrer noopener\">http:\/\/www.aboutads.info\/choices\/<\/a>\u00a0oder die EU-Seite\u00a0<a href=\"http:\/\/www.youronlinechoices.com\/\" target=\"_blank\" rel=\"noreferrer noopener\">http:\/\/www.youronlinechoices.com\/<\/a>\u00a0erkl\u00e4rt werden. Des Weiteren kann die Speicherung von Cookies mittels deren Abschaltung in den Einstellungen des Browsers erreicht werden. Bitte beachten Sie, dass dann gegebenenfalls nicht alle Funktionen dieses Onlineangebotes genutzt werden k\u00f6nnen.<\/p>\n<p><strong>Datenschutzerkl\u00e4rung f\u00fcr SSL-\/TLS-Verschl\u00fcsselung<br \/><\/strong>Diese Website nutzt aus Gr\u00fcnden der Sicherheit und zum Schutz der \u00dcbertragung vertraulicher Inhalte, wie zum Beispiel der Anfragen, die Sie an uns als Seitenbetreiber senden, eine SSL-\/TLS-Verschl\u00fcsselung. Eine verschl\u00fcsselte Verbindung erkennen Sie daran, dass die Adresszeile des Browsers von \u201ehttp:\/\/\u201c auf \u201ehttps:\/\/\u201c wechselt und an dem Schloss-Symbol in Ihrer Browserzeile.<\/p>\n<p>Wenn die SSL bzw. TLS Verschl\u00fcsselung aktiviert ist, k\u00f6nnen die Daten, die Sie an uns \u00fcbermitteln, nicht von Dritten mitgelesen werden.<\/p>\n<p><strong>Datenschutzerkl\u00e4rung f\u00fcr Server-Log-Files<br \/><\/strong>Der Provider dieser Website erhebt und speichert automatisch Informationen in so genannten Server-Log Files, die Ihr Browser automatisch an uns \u00fcbermittelt. Dies sind:<\/p>\n<ul>\n<li>Browsertyp und Browserversion<\/li>\n<li>verwendetes Betriebssystem<\/li>\n<li>Referrer URL<\/li>\n<li>Hostname des zugreifenden Rechners<\/li>\n<li>Uhrzeit der Serveranfrage<\/li>\n<\/ul>\n<p>Diese Daten sind nicht bestimmten Personen zuordenbar. Eine Zusammenf\u00fchrung dieser Daten mit anderen Datenquellen wird nicht vorgenommen. Wir behalten uns vor, diese Daten nachtr\u00e4glich zupr\u00fcfen, wenn uns konkrete Anhaltspunkte f\u00fcr eine rechtswidrige Nutzung bekannt werden.<\/p>\n<p><strong>Dienste von Dritten<br \/><\/strong>Diese Website verwenden allenfalls Google Maps f\u00fcr das Einbetten von Karten, Google Invisible reCAPTCHA f\u00fcr den Schutz gegen Bots und Spam sowie YouTube f\u00fcr das Einbetten von Videos.<\/p>\n<p>Diese Dienste der amerikanischen Google LLC verwenden unter anderem Cookies und infolgedessen werden Daten an Google in den USA \u00fcbertragen, wobei wir davon ausgehen, dass in diesem Rahmen kein personenbezogenes Tracking allein durch die Nutzung unserer Website stattfindet.<\/p>\n<p>Google hat sich verpflichtet, einen angemessenen Datenschutz gem\u00e4ss dem amerikanisch-europ\u00e4ischen und dem amerikanisch-schweizerischen Privacy Shield zu gew\u00e4hrleisten.<\/p>\n<p>Weitere Informationen finden sich in der\u00a0<a href=\"https:\/\/policies.google.com\/privacy?hl=de\" target=\"_blank\" rel=\"noreferrer noopener\">Datenschutzerkl\u00e4rung von Google<\/a>.<\/p>\n<p><strong>Datenschutzerkl\u00e4rung f\u00fcr Kontaktformular<br \/><\/strong>Wenn Sie uns per Kontaktformular Anfragen zukommen lassen, werden Ihre Angaben aus dem Anfrageformular inklusive der von Ihnen dort angegebenen Kontaktdaten zwecks Bearbeitung der Anfrage und f\u00fcr den Fall von Anschlussfragen bei uns gespeichert. Diese Daten geben wir nicht ohne Ihre Einwilligung weiter.<\/p>\n<p><strong>Datenschutzerkl\u00e4rung f\u00fcr Newsletterdaten<br \/><\/strong>Wenn Sie den auf dieser Website angebotenen Newsletter beziehen m\u00f6chten, ben\u00f6tigen wir von Ihnen eine E-Mail-Adresse sowie Informationen, welche uns die \u00dcberpr\u00fcfung gestatten, dass Sie der Inhaber der angegebenen E-Mail-Adresse sind und mit dem Empfang des Newsletters einverstanden sind. Weitere Daten werden nicht erhoben. Diese Daten verwenden wir ausschliesslich f\u00fcr den Versand der angeforderten Informationen und geben sie nicht an Dritte weiter.<\/p>\n<p>Die erteilte Einwilligung zur Speicherung der Daten, der E-Mail-Adresse sowie deren Nutzung zum Versand des Newsletters k\u00f6nnen Sie jederzeit widerrufen, etwa \u00fcber den \u00abAustragen-Link\u00bb im Newsletter.<\/p>\n<p><strong>Datenschutzerkl\u00e4rung f\u00fcr Kommentarfunktion auf dieser Website<br \/><\/strong>F\u00fcr die Kommentarfunktion auf dieser Website werden neben Ihrem Kommentar auch Angaben zum Zeitpunkt der Erstellung des Kommentars, Ihre E-Mail-Adresse und, wenn Sie nicht anonym posten, der von Ihnen gew\u00e4hlte Nutzername gespeichert.<\/p>\n<p><em>Speicherung der IP Adresse<\/em><\/p>\n<p>Unsere Kommentarfunktion speichert die IP-Adressen der Nutzer, die Kommentare verfassen. Da wir Kommentare auf unserer Seite nicht vor der Freischaltung pr\u00fcfen, ben\u00f6tigen wir diese Daten, um im Falle von Rechtsverletzungen wie Beleidigungen oder Propaganda gegen den Verfasser vorgehen zu k\u00f6nnen.<\/p>\n<p><em>Abonnieren von Kommentaren<\/em><\/p>\n<p>Als Nutzer der Seite k\u00f6nnen Sie nach einer Anmeldung Kommentare abonnieren. Sie erhalten eine Best\u00e4tigungsemail, um zu pr\u00fcfen, ob Sie der Inhaber der angegebenen E-Mail-Adresse sind. Sie k\u00f6nnen diese Funktion jederzeit \u00fcber einen Link in den Info-Mails abbestellen.<\/p>\n<p><strong>Datenschutzerkl\u00e4rung f\u00fcr Widerspruch Werbe-Mails<br \/><\/strong>Der Nutzung von im Rahmen der Impressumspflicht ver\u00f6ffentlichten Kontaktdaten zur \u00dcbersendung von nicht ausdr\u00fccklich angeforderter Werbung und Informationsmaterialien wird hiermit widersprochen. Die Betreiber der Seiten behalten sich ausdr\u00fccklich rechtliche Schritte im Falle der unverlangten Zusendung von Werbeinformationen, etwa durch Spam-E-Mails, vor.<\/p>\n<p><strong>Kostenpflichtige Leistungen<br \/><\/strong>Zur Erbringung kostenpflichtiger Leistungen werden von uns zus\u00e4tzliche Daten erfragt, wie z.B. Zahlungsangaben, um Ihre Bestellung resp. Ihren Auftrag ausf\u00fchren zu k\u00f6nnen. Wir speichern diese Daten in unseren Systemen, bis die gesetzlichen Aufbewahrungsfristen abgelaufen sind.<\/p>\n<p><strong>Verwendung von Google Maps<br \/><\/strong>Diese Website nutzt das Angebot von Google Maps. Dadurch k\u00f6nnen wir Ihnen interaktive Karten direkt in der Website anzeigen und erm\u00f6glichen Ihnen die komfortable Nutzung der Karten-Funktion. Durch den Besuch auf der Website erh\u00e4lt Google die Information, dass Sie die entsprechende Unterseite unserer Website aufgerufen haben. Dies erfolgt unabh\u00e4ngig davon, ob Google ein Nutzerkonto bereitstellt, \u00fcber das Sie eingeloggt sind, oder ob kein Nutzerkonto besteht. Wenn Sie bei Google eingeloggt sind, werden Ihre Daten direkt Ihrem Konto zugeordnet. Wenn Sie die Zuordnung mit Ihrem Profil bei Google nicht w\u00fcnschen, m\u00fcssen Sie sich vor Aktivierung des Buttons ausloggen. Google speichert Ihre Daten als Nutzungsprofile und nutzt sie f\u00fcr Zwecke der Werbung, Marktforschung und\/oder bedarfsgerechten Gestaltung seiner Website. Eine solche Auswertung erfolgt insbesondere (selbst f\u00fcr nicht eingeloggte Nutzer) zur Erbringung von bedarfsgerechter Werbung und um andere Nutzer des sozialen Netzwerks \u00fcber Ihre Aktivit\u00e4ten auf unserer Website zu informieren. Ihnen steht ein Widerspruchsrecht zu gegen die Bildung dieser Nutzerprofile, wobei Sie sich zur Aus\u00fcbung dessen an Google richten m\u00fcssen. Weitere Informationen zu Zweck und Umfang der Datenerhebung und ihrer Verarbeitung durch Google erhalten Sie neben weiteren Informationen zu Ihren diesbez\u00fcglichen Rechten und Einstellungsm\u00f6glichkeiten zum Schutze Ihrer Privatsph\u00e4re unter:\u00a0<a href=\"http:\/\/www.google.de\/intl\/de\/policies\/privacy\" target=\"_blank\" rel=\"noreferrer noopener\">www.google.de\/intl\/de\/policies\/privacy<\/a>.<\/p>\n<p><strong>Datenschutzerkl\u00e4rung f\u00fcr YouTube<br \/><\/strong>Auf dieser Website sind Funktionen des Dienstes \u00abYouTube\u00bb eingebunden. \u00abYouTube\u00bb geh\u00f6rt der Google Ireland Limited, einer nach irischem Recht eingetragenen und betriebenen Gesellschaft mit Sitz in Gordon House, Barrow Street, Dublin 4, Irland, welche die Dienste im Europ\u00e4ischen Wirtschaftsraum und der Schweiz betreibt.<\/p>\n<p>Ihre rechtliche Vereinbarung mit \u00abYouTube\u00bb besteht aus den unter folgendem Link zu entnehmenden Bestimmungen und Bedingungen:\u00a0<a href=\"https:\/\/www.youtube.com\/static?gl=DE&amp;template=terms&amp;hl=de\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.youtube.com\/static?gl=de&amp;template=terms&amp;hl=de<\/a>. Diese Bestimmungen bilden eine rechtlich bindende Vereinbarung zwischen Ihnen und \u00abYouTube\u00bb bez\u00fcglich der Nutzung der Dienste. In der Datenschutzerkl\u00e4rung von Google wird erl\u00e4utert, wie \u00abYouTube\u00bb mit Ihren personenbezogenen Daten verf\u00e4hrt und Ihre Daten sch\u00fctzt, wenn Sie den Dienst nutzen.<\/p>\n<p><strong>Bestellabwicklung im Online-Shop mit Kundenkonto<br \/><\/strong>Wir verarbeiten die Daten unserer Kunden gem. den datenschutzrechtlichen Bestimmungen des Bundes (Datenschutzgesetz, DSG) und der EU-DSGVO, im Rahmen der Bestellvorg\u00e4nge in unserem Onlineshop, um ihnen die Auswahl und die Bestellung der gew\u00e4hlten Produkte und Leistungen, sowie deren Bezahlung und Zustellung, bzw. Ausf\u00fchrung zu erm\u00f6glichen.<\/p>\n<p>Zu den verarbeiteten Daten geh\u00f6ren Stammdaten (Bestandsdaten), Kommunikationsdaten, Vertragsdaten, Zahlungsdaten und zu den von der Verarbeitung betroffenen Personen geh\u00f6ren unsere Kunden, Interessenten und sonstige Gesch\u00e4ftspartner. Die Verarbeitung erfolgt zum Zweck der Erbringung von Vertragsleistungen im Rahmen des Betriebs eines Onlineshops, Abrechnung, Auslieferung und der Kundenservices. Hierbei setzen wir Session Cookies, z.B. f\u00fcr die Speicherung des Warenkorb-Inhalts und permanente Cookies, z.B. f\u00fcr die Speicherung des Login-Status ein.<\/p>\n<p>Die Verarbeitung erfolgt auf Grundlage des Art. 6 Abs. 1 lit. b (Durchf\u00fchrung Bestellvorg\u00e4nge) und c (Gesetzlich erforderliche Archivierung) DSGVO. Dabei sind die als erforderlich gekennzeichneten Angaben zur Begr\u00fcndung und Erf\u00fcllung des Vertrages erforderlich. Die Daten offenbaren wir gegen\u00fcber Dritten nur im Rahmen der Auslieferung, Zahlung oder im Rahmen der gesetzlichen Erlaubnisse und Pflichten. Die Daten werden in Drittl\u00e4ndern nur dann verarbeitet, wenn dies zur Vertragserf\u00fcllung erforderlich ist (z.B. auf Kundenwunsch bei Auslieferung oder Zahlung).<\/p>\n<p>Nutzer k\u00f6nnen optional ein Nutzerkonto anlegen, indem sie insbesondere ihre Bestellungen einsehen k\u00f6nnen. Im Rahmen der Registrierung, werden die erforderlichen Pflichtangaben den Nutzern mitgeteilt. Die Nutzerkonten sind nicht \u00f6ffentlich und k\u00f6nnen von Suchmaschinen, z.B. Google, nicht indexiert werden. Wenn Nutzer ihr Nutzerkonto gek\u00fcndigt haben, werden deren Daten im Hinblick auf das Nutzerkonto gel\u00f6scht, vorbehaltlich deren Aufbewahrung ist aus handels- oder steuerrechtlichen Gr\u00fcnden entspr. Art. 6 Abs. 1 lit. c DSGVO notwendig. Angaben im Kundenkonto verbleiben bis zu deren L\u00f6schung mit anschliessender Archivierung im Fall einer rechtlichen Verpflichtung. Es obliegt den Nutzern, ihre Daten bei erfolgter K\u00fcndigung vor dem Vertragsende zu sichern.<\/p>\n<p>Im Rahmen der Registrierung und erneuter Anmeldungen sowie Inanspruchnahme unserer Onlinedienste, speichern wir die IP-Adresse und den Zeitpunkt der jeweiligen Nutzerhandlung. Die Speicherung erfolgt auf Grundlage unserer berechtigten Interessen, als auch der Nutzer an Schutz vor Missbrauch und sonstiger unbefugter Nutzung. Eine Weitergabe dieser Daten an Dritte erfolgt grunds\u00e4tzlich nicht, ausser sie ist zur Verfolgung unserer Anspr\u00fcche erforderlich oder es besteht hierzu eine gesetzliche Verpflichtung gem. Art. 6 Abs. 1 lit. c DSGVO.<\/p>\n<p>Die L\u00f6schung erfolgt nach Ablauf gesetzlicher Gew\u00e4hrleistungs- und vergleichbarer Pflichten, die Erforderlichkeit der Aufbewahrung der Daten wird in unregelm\u00e4ssigen Abst\u00e4nden \u00fcberpr\u00fcft. Im Fall der gesetzlichen Archivierungspflichten erfolgt die L\u00f6schung nach deren Ablauf.<\/p>\n<p><strong>Urheberrechte<br \/><\/strong>Die Urheber- und alle anderen Rechte an Inhalten, Bildern, Fotos oder anderen Dateien auf der Website, geh\u00f6ren ausschliesslich dem Betreiber dieser Website oder den speziell genannten Rechteinhabern. F\u00fcr die Reproduktion von s\u00e4mtlichen Dateien, ist die schriftliche Zustimmung des Urheberrechtstr\u00e4gers im Voraus einzuholen.<\/p>\n<p>Wer ohne Einwilligung des jeweiligen Rechteinhabers eine Urheberrechtsverletzung begeht, kann sich strafbar und allenfalls schadenersatzpflichtig machen.<\/p>\n<p><strong>Allgemeiner Haftungsausschluss<br \/><\/strong>Alle Angaben unseres Internetangebotes wurden sorgf\u00e4ltig gepr\u00fcft. Wir bem\u00fchen uns, unser Informationsangebot aktuell, inhaltlich richtig und vollst\u00e4ndig anzubieten. Trotzdem kann das Auftreten von Fehlern nicht v\u00f6llig ausgeschlossen werden, womit wir keine Garantie f\u00fcr Vollst\u00e4ndigkeit, Richtigkeit und Aktualit\u00e4t von Informationen auch journalistisch-redaktioneller Art \u00fcbernehmen k\u00f6nnen. Haftungsanspr\u00fcche aus Sch\u00e4den materieller oder ideeller Art, die durch die Nutzung der angebotenen Informationen verursacht wurden, sind ausgeschlossen, sofern kein nachweislich vors\u00e4tzliches oder grob fahrl\u00e4ssiges Verschulden vorliegt.<\/p>\n<p>Der Herausgeber kann nach eigenem Ermessen und ohne Ank\u00fcndigung Texte ver\u00e4ndern oder l\u00f6schen und ist nicht verpflichtet, Inhalte dieser Website zu aktualisieren. Die Benutzung bzw. der Zugang zu dieser Website geschieht auf eigene Gefahr des Besuchers. Der Herausgeber, seine Auftraggeber oder Partner sind nicht verantwortlich f\u00fcr Sch\u00e4den, wie direkte, indirekte, zuf\u00e4llige, vorab konkret zu bestimmende oder Folgesch\u00e4den, die angeblich durch den Besuch dieser Website entstanden sind und \u00fcbernehmen hierf\u00fcr folglich keine Haftung.<\/p>\n<p>Der Herausgeber \u00fcbernimmt ebenfalls keine Verantwortung und Haftung f\u00fcr die Inhalte und die Verf\u00fcgbarkeit von Website Dritter, die \u00fcber externe Links dieser Website erreichbar sind. F\u00fcr den Inhalt der verlinkten Seiten sind ausschliesslich deren Betreiber verantwortlich. Der Herausgeber distanziert sich damit ausdr\u00fccklich von allen Inhalten Dritter, die m\u00f6glicherweise straf- oder haftungsrechtlich relevant sind oder gegen die guten Sitten verstossen.<\/p>\n<p><strong>\u00c4nderungen<br \/><\/strong>Wir k\u00f6nnen diese Datenschutzerkl\u00e4rung jederzeit ohne Vorank\u00fcndigung anpassen. Es gilt die jeweils aktuelle, auf unserer Website publizierte Fassung. Soweit die Datenschutzerkl\u00e4rung Teil einer Vereinbarung mit Ihnen ist, werden wir Sie im Falle einer Aktualisierung \u00fcber die \u00c4nderung per E-Mail oder auf andere geeignete Weise informieren.<\/p>\n<p><strong>Fragen an den Datenschutzbeauftragten<br \/><\/strong>Wenn Sie Fragen zum Datenschutz haben, schreiben Sie uns bitte eine E-Mail oder wenden Sie sich direkt an die f\u00fcr den Datenschutz zu Beginn der Datenschutzerkl\u00e4rung aufgef\u00fchrten, verantwortlichen Person in unserer Organisation.<\/p>\n<p>Auw, 19.08.2024<br \/>Quelle:\u00a0<a rel=\"noreferrer noopener\" href=\"https:\/\/www.swissanwalt.ch\/\" target=\"_blank\">SwissAnwalt<\/a><\/p>\n<p>[\/et_pb_text][et_pb_code _builder_version=&#8220;4.24.0&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;]<p id=\"matomo_opted_out_intro\" style=\"display:none;\">Opt-out complete; your visits to this website will not be recorded by the Web Analytics tool. Note that if you clear your cookies, delete the opt-out cookie, or if you change computers or Web browsers, you will need to perform the opt-out procedure again.<\/p><p id=\"matomo_opted_in_intro\" >You may choose to prevent this website from aggregating and analyzing the actions you take here. Doing so will protect your privacy, but will also prevent the owner from learning from your actions and creating a better experience for you and other users.<\/p><form>\n        <input type=\"checkbox\" id=\"matomo_optout_checkbox\" checked=\"checked\"\/>\n        <label for=\"matomo_optout_checkbox\"><strong>\n        <span id=\"matomo_opted_in_label\" >You are not opted out. Uncheck this box to opt-out.<\/span>\n\t\t<span id=\"matomo_opted_out_label\" style=\"display:none;\">You are currently opted out. Check this box to opt-in.<\/span>\n        <\/strong><\/label><\/form><noscript><p><strong style=\"color: #ff0000;\">This opt out feature requires JavaScript.<\/strong><\/p><\/noscript><p id=\"matomo_outout_err_cookies\" style=\"display: none;\"><strong>The tracking opt-out feature requires cookies to be enabled.<\/strong><\/p>[\/et_pb_code][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8220;1&#8243; fullwidth=&#8220;on&#8220; _builder_version=&#8220;4.21.0&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_fullwidth_image _builder_version=&#8220;4.21.0&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_fullwidth_image][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Datenschutzerkl\u00e4rung Verantwortliche Stelle im Sinne der Datenschutzgesetze, insbesondere der EU-Datenschutzgrundverordnung (DSGVO), ist: HC RigiStrasse, Nr,PLZ Ort E-Mail: <a href=\"mailto:i&#110;&#102;&#111;&#64;h&#99;&#114;&#105;&#103;i&#46;&#99;&#104;\">&#105;&#110;f&#111;&#64;hcrigi&#46;c&#104;<\/a>WebSite: https:\/\/www.hcrigi.ch Allgemeiner HinweisGest\u00fctzt auf Artikel 13 der schweizerischen Bundesverfassung und den datenschutzrechtlichen [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"open","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"<!-- wp:heading -->\n<h2 class=\"wp-block-heading\">Wer wir sind<\/h2>\n<!-- \/wp:heading -->\n<!-- wp:paragraph -->\n<p><strong class=\"privacy-policy-tutorial\">Textvorschlag: <\/strong>Die Adresse unserer Website ist: https:\/\/hcrigi.ch.<\/p>\n<!-- \/wp:paragraph -->\n<!-- wp:heading -->\n<h2 class=\"wp-block-heading\">Kommentare<\/h2>\n<!-- \/wp:heading -->\n<!-- wp:paragraph -->\n<p><strong class=\"privacy-policy-tutorial\">Textvorschlag: <\/strong>Wenn Besucher Kommentare auf der Website schreiben, sammeln wir die Daten, die im Kommentar-Formular angezeigt werden, ausserdem die IP-Adresse des Besuchers und den User-Agent-String (damit wird der Browser identifiziert), um die Erkennung von Spam zu unterst\u00fctzen.<\/p>\n<!-- \/wp:paragraph -->\n<!-- wp:paragraph -->\n<p>Aus Ihrer E-Mail-Adresse kann eine anonymisierte Zeichenfolge erstellt (auch Hash genannt) und dem Gravatar-Dienst \u00fcbergeben werden, um zu pr\u00fcfen, ob Sie diesen benutzt. Die Datenschutzerkl\u00e4rung des Gravatar-Dienstes finden Sie hier: https:\/\/automattic.com\/privacy\/. Nachdem Ihr Kommentar freigegeben wurde, ist Ihr Profilbild \u00f6ffentlich im Kontext Ihres Kommentars sichtbar.<\/p>\n<!-- \/wp:paragraph -->\n<!-- wp:heading -->\n<h2 class=\"wp-block-heading\">Medien<\/h2>\n<!-- \/wp:heading -->\n<!-- wp:paragraph -->\n<p><strong class=\"privacy-policy-tutorial\">Textvorschlag: <\/strong>Wenn Sie ein registrierter Benutzer sind und Fotos auf diese Website laden, sollten Sie vermeiden, Fotos mit einem EXIF-GPS-Standort hochzuladen. Besucher dieser Website k\u00f6nnten Fotos, die auf dieser Website gespeichert sind, herunterladen und deren Standort-Informationen extrahieren.<\/p>\n<!-- \/wp:paragraph -->\n<!-- wp:heading -->\n<h2 class=\"wp-block-heading\">Cookies<\/h2>\n<!-- \/wp:heading -->\n<!-- wp:paragraph -->\n<p><strong class=\"privacy-policy-tutorial\">Textvorschlag: <\/strong>Wenn Sie einen Kommentar auf unserer Website schreiben, kann das eine Einwilligung sein, Ihren Namen, E-Mail-Adresse und Website in Cookies zu speichern. Dies ist eine Komfortfunktion, damit Sie nicht, wenn Sie einen weiteren Kommentar schreiben, all diese Daten erneut eingeben m\u00fcssen. Diese Cookies werden ein Jahr lang gespeichert.<\/p>\n<!-- \/wp:paragraph -->\n<!-- wp:paragraph -->\n<p>Falls Sie ein Konto haben und Sie sich auf dieser Website anmelden, werden wir ein tempor\u00e4res Cookie setzen, um festzustellen, ob Ihr Browser Cookies akzeptiert. Dieses Cookie enth\u00e4lt keine personenbezogenen Daten und wird verworfen, wenn Sie Ihren Browser schliessen.<\/p>\n<!-- \/wp:paragraph -->\n<!-- wp:paragraph -->\n<p>Wenn Sie sich anmelden, werden wir einige Cookies einrichten, um Ihre Anmeldeinformationen und Anzeigeoptionen zu speichern. Anmelde-Cookies verfallen nach zwei Tagen und Cookies f\u00fcr die Anzeigeoptionen nach einem Jahr. Falls Sie bei der Anmeldung \u00abAngemeldet bleiben\u00bb ausw\u00e4hlen, wird Ihre Anmeldung zwei Wochen lang aufrechterhalten. Mit der Abmeldung aus Ihrem Konto werden die Anmelde-Cookies gel\u00f6scht.<\/p>\n<!-- \/wp:paragraph -->\n<!-- wp:paragraph -->\n<p>Wenn Sie einen Artikel bearbeiten oder ver\u00f6ffentlichen, wird ein zus\u00e4tzlicher Cookie in Ihrem Browser gespeichert. Dieser Cookie enth\u00e4lt keine personenbezogenen Daten und verweist nur auf die Beitrags-ID des Artikels, den Sie gerade bearbeitet haben. Der Cookie verf\u00e4llt nach einem Tag.<\/p>\n<!-- \/wp:paragraph -->\n<!-- wp:heading -->\n<h2 class=\"wp-block-heading\">Eingebettete Inhalte von anderen Websites<\/h2>\n<!-- \/wp:heading -->\n<!-- wp:paragraph -->\n<p><strong class=\"privacy-policy-tutorial\">Textvorschlag: <\/strong>Beitr\u00e4ge auf dieser Website k\u00f6nnen eingebettete Inhalte beinhalten (z.\u00a0B. Videos, Bilder, Beitr\u00e4ge etc.). Eingebettete Inhalte von anderen Websites verhalten sich exakt so, als ob der Besucher die andere Website besucht h\u00e4tte.<\/p>\n<!-- \/wp:paragraph -->\n<!-- wp:paragraph -->\n<p>Diese Websites k\u00f6nnen Daten \u00fcber Sie sammeln, Cookies benutzen, zus\u00e4tzliche Tracking-Dienste von Dritten einbetten und Ihre Interaktion mit diesem eingebetteten Inhalt aufzeichnen, inklusive Ihrer Interaktion mit dem eingebetteten Inhalt, falls Sie ein Konto haben und auf dieser Website angemeldet sind.<\/p>\n<!-- \/wp:paragraph -->\n<!-- wp:heading -->\n<h2 class=\"wp-block-heading\">Mit wem wir Ihre Daten teilen<\/h2>\n<!-- \/wp:heading -->\n<!-- wp:paragraph -->\n<p><strong class=\"privacy-policy-tutorial\">Textvorschlag: <\/strong>Wenn Sie eine Zur\u00fccksetzung des Passworts beantragen, wird Ihre IP-Adresse in der E-Mail zur Zur\u00fccksetzung enthalten sein.<\/p>\n<!-- \/wp:paragraph -->\n<!-- wp:heading -->\n<h2 class=\"wp-block-heading\">Wie lange wir Ihre Daten speichern<\/h2>\n<!-- \/wp:heading -->\n<!-- wp:paragraph -->\n<p><strong class=\"privacy-policy-tutorial\">Textvorschlag: <\/strong>Wenn Sie einen Kommentar schreiben, wird dieser inklusive Metadaten zeitlich unbegrenzt gespeichert. Auf diese Art k\u00f6nnen wir Folgekommentare automatisch erkennen und freigeben, anstatt sie in einer Moderations-Warteschlange festzuhalten.<\/p>\n<!-- \/wp:paragraph -->\n<!-- wp:paragraph -->\n<p>F\u00fcr Benutzer, die sich auf unserer Website registrieren, speichern wir zus\u00e4tzlich die pers\u00f6nlichen Informationen, die sie in ihren Benutzerprofilen angeben. Alle Benutzer k\u00f6nnen jederzeit ihre pers\u00f6nlichen Informationen einsehen, ver\u00e4ndern oder l\u00f6schen (der Benutzername kann nicht ver\u00e4ndert werden). Administratoren der Website k\u00f6nnen diese Informationen ebenfalls einsehen und ver\u00e4ndern.<\/p>\n<!-- \/wp:paragraph -->\n<!-- wp:heading -->\n<h2 class=\"wp-block-heading\">Welche Rechte Sie an Ihren Daten haben<\/h2>\n<!-- \/wp:heading -->\n<!-- wp:paragraph -->\n<p><strong class=\"privacy-policy-tutorial\">Textvorschlag: <\/strong>Wenn Sie ein Konto auf dieser Website besitzen oder Kommentare geschrieben haben, k\u00f6nnen Sie einen Export Ihrer personenbezogenen Daten bei uns anfordern, inklusive aller Daten, die Sie uns mitgeteilt haben. Dar\u00fcber hinaus k\u00f6nnen Sie die L\u00f6schung aller personenbezogenen Daten, die wir von Ihnen gespeichert haben, anfordern. Dies umfasst nicht die Daten, die wir aufgrund administrativer, rechtlicher oder sicherheitsrelevanter Notwendigkeiten aufbewahren m\u00fcssen.<\/p>\n<!-- \/wp:paragraph -->\n<!-- wp:heading -->\n<h2 class=\"wp-block-heading\">Wohin Ihre Daten gesendet werden<\/h2>\n<!-- \/wp:heading -->\n<!-- wp:paragraph -->\n<p><strong class=\"privacy-policy-tutorial\">Textvorschlag: <\/strong>Besucher-Kommentare k\u00f6nnten von einem automatisierten Dienst zur Spam-Erkennung untersucht werden.<\/p>\n<!-- \/wp:paragraph -->\n","_et_gb_content_width":"","footnotes":""},"class_list":["post-3","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/hcrigi.ch\/index.php\/wp-json\/wp\/v2\/pages\/3","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hcrigi.ch\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/hcrigi.ch\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/hcrigi.ch\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/hcrigi.ch\/index.php\/wp-json\/wp\/v2\/comments?post=3"}],"version-history":[{"count":4,"href":"https:\/\/hcrigi.ch\/index.php\/wp-json\/wp\/v2\/pages\/3\/revisions"}],"predecessor-version":[{"id":2586,"href":"https:\/\/hcrigi.ch\/index.php\/wp-json\/wp\/v2\/pages\/3\/revisions\/2586"}],"wp:attachment":[{"href":"https:\/\/hcrigi.ch\/index.php\/wp-json\/wp\/v2\/media?parent=3"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}